{"id":1517,"date":"2025-09-17T09:29:34","date_gmt":"2025-09-17T06:29:34","guid":{"rendered":"https:\/\/www.agora-platform.eu\/conference2025\/?page_id=1517"},"modified":"2025-09-17T09:33:55","modified_gmt":"2025-09-17T06:33:55","slug":"ga-agenda","status":"publish","type":"page","link":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/","title":{"rendered":"GA Agenda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1517\" class=\"elementor elementor-1517\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc61bc0 e-flex e-con-boxed e-con e-parent\" data-id=\"fc61bc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a62e57 elementor-widget elementor-widget-spacer\" data-id=\"6a62e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f5b227 e-flex e-con-boxed e-con e-parent\" data-id=\"8f5b227\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8337bbe elementor-widget elementor-widget-image\" data-id=\"8337bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg\" class=\"attachment-large size-large wp-image-1519\" alt=\"\" srcset=\"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg 2560w, https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-768x432.jpg 768w, https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-1536x864.jpg 1536w, https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-2048x1152.jpg 2048w, https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-600x338.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05df07b e-flex e-con-boxed e-con e-parent\" data-id=\"05df07b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39377bd elementor-widget elementor-widget-text-editor\" data-id=\"39377bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\">Download the Agenda <a href=\"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA.pdf\">here<\/a><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1e2e74 e-flex e-con-boxed e-con e-parent\" data-id=\"d1e2e74\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b4efaa elementor-widget elementor-widget-spacer\" data-id=\"7b4efaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Download the Agenda here<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1517","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GA Agenda - Agora Annual Conference 2025<\/title>\n<meta name=\"description\" content=\"Download the Agenda here...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GA Agenda - Agora Annual Conference 2025\" \/>\n<meta property=\"og:description\" content=\"Download the Agenda here...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/\" \/>\n<meta property=\"og:site_name\" content=\"Agora Annual Conference 2025\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T06:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u03bb\u03b5\u03c0\u03c4\u03cc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/\",\"url\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/\",\"name\":\"GA Agenda - Agora Annual Conference 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/AGORA-GA-AGENDA-scaled.jpg\",\"datePublished\":\"2025-09-17T06:29:34+00:00\",\"dateModified\":\"2025-09-17T06:33:55+00:00\",\"description\":\"Download the Agenda here...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/AGORA-GA-AGENDA-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/AGORA-GA-AGENDA-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/ga-agenda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GA Agenda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/#website\",\"url\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/\",\"name\":\"Agora Annual Conference 2025\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.agora-platform.eu\\\/conference2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GA Agenda - Agora Annual Conference 2025","description":"Download the Agenda here...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"el_GR","og_type":"article","og_title":"GA Agenda - Agora Annual Conference 2025","og_description":"Download the Agenda here...","og_url":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/","og_site_name":"Agora Annual Conference 2025","article_modified_time":"2025-09-17T06:33:55+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2":"1 \u03bb\u03b5\u03c0\u03c4\u03cc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/","url":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/","name":"GA Agenda - Agora Annual Conference 2025","isPartOf":{"@id":"https:\/\/www.agora-platform.eu\/conference2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/#primaryimage"},"image":{"@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg","datePublished":"2025-09-17T06:29:34+00:00","dateModified":"2025-09-17T06:33:55+00:00","description":"Download the Agenda here...","breadcrumb":{"@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/#primaryimage","url":"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg","contentUrl":"https:\/\/www.agora-platform.eu\/conference2025\/wp-content\/uploads\/2025\/09\/AGORA-GA-AGENDA-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.agora-platform.eu\/conference2025\/ga-agenda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/www.agora-platform.eu\/conference2025\/"},{"@type":"ListItem","position":2,"name":"GA Agenda"}]},{"@type":"WebSite","@id":"https:\/\/www.agora-platform.eu\/conference2025\/#website","url":"https:\/\/www.agora-platform.eu\/conference2025\/","name":"Agora Annual Conference 2025","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.agora-platform.eu\/conference2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"}]}},"_links":{"self":[{"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/pages\/1517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/comments?post=1517"}],"version-history":[{"count":6,"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/pages\/1517\/revisions"}],"predecessor-version":[{"id":1527,"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/pages\/1517\/revisions\/1527"}],"wp:attachment":[{"href":"https:\/\/www.agora-platform.eu\/conference2025\/wp-json\/wp\/v2\/media?parent=1517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}